{"id":1907,"date":"2022-04-21T16:17:37","date_gmt":"2022-04-21T16:17:37","guid":{"rendered":"https:\/\/www.mundorunning.cl\/app\/?p=1907"},"modified":"2022-04-21T16:27:06","modified_gmt":"2022-04-21T16:27:06","slug":"jbarreraboston22","status":"publish","type":"post","link":"https:\/\/www.mundorunning.cl\/app\/running\/jbarreraboston22\/","title":{"rendered":"BOSTON MARATHON 2022: \u00abEn el kil\u00f3metro 35 baj\u00e9 la cabeza y pens\u00e9 en parar, pero escuch\u00e9 un grito&#8230;\u00bb"},"content":{"rendered":"\n<p>Soy <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/src_pantera\/\" data-type=\"URL\" data-id=\"https:\/\/www.instagram.com\/src_pantera\/\" target=\"_blank\">Jonathan Barrera<\/a><\/strong>, maratonista, y entreno en<a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/stgorunners\/\" data-type=\"URL\" data-id=\"https:\/\/www.instagram.com\/stgorunners\/\" target=\"_blank\"> <strong>Santiago Runners<\/strong><\/a>. Para estar presente en <strong><em>\u00abBoston Marathon\u00bb<\/em><\/strong>, viaj\u00e9 el viernes en la noche pensando llegar el s\u00e1bado en la ma\u00f1ana y poder retirar el kit de competencia temprano, pero el destino me ten\u00eda preparado algo distinto, ya que me cancelaron el vuelo de <strong>Miami<\/strong> a<strong> Boston <\/strong>a las 6 de la ma\u00f1ana. Luego qued\u00e9 en lista de espera de dos vuelos m\u00e1s, pero el aeropuerto estaba lleno de atletas que estaban igual que yo&#8230; Cuento corto, reci\u00e9n viaj\u00e9 a <strong>Boston<\/strong> a las 18:00 horas, muy cansado y con el d\u00eda perdido en el aeropuerto, pero sab\u00eda que eso ya me har\u00eda m\u00e1s fuerte para correr el lunes, as\u00ed que siempre vi el vaso medio lleno. Sab\u00eda que todo lo que pasara jugar\u00eda a mi favor. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>El domingo sal\u00ed a entrenar normal y luego a retirar el n\u00famero de competencia, miles de personas iban a buscar lo mismo que yo, no s\u00f3lo un n\u00famero, sino m\u00e1s bien la <em>coronaci\u00f3n de un proceso<\/em>, ojal\u00e1 todos lo hayan logrado. <\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/www.instagram.com\/src_pantera\/\" data-type=\"URL\" data-id=\"https:\/\/www.instagram.com\/src_pantera\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" width=\"876\" height=\"582\" class=\"wp-image-1908\" style=\"width: 500px;\" src=\"https:\/\/www.mundorunning.cl\/app\/wp-content\/uploads\/2022\/04\/JBarreraBoston22.jpeg\" alt=\"\" srcset=\"https:\/\/www.mundorunning.cl\/app\/wp-content\/uploads\/2022\/04\/JBarreraBoston22.jpeg 876w, https:\/\/www.mundorunning.cl\/app\/wp-content\/uploads\/2022\/04\/JBarreraBoston22-300x199.jpeg 300w, https:\/\/www.mundorunning.cl\/app\/wp-content\/uploads\/2022\/04\/JBarreraBoston22-768x510.jpeg 768w\" sizes=\"(max-width: 876px) 100vw, 876px\" \/><\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>El lunes me levante a las 5 AM, unas tostadas y un t\u00e9 fue mi desayuno, y a tomar el metro para llegar al punto de encuentro a las 6:45 hrs. <br>Ah\u00ed sal\u00edan buses para el punto de partida, mi corral era el n\u00famero 2, ya en el bus se ve\u00eda que correr un marat\u00f3n es una gran distancia, esperamos unas horas en un gran colegio cerca de la partida que comenzaba a las 10:00 en punto, y ac\u00e1 mi experiencia m\u00e1s linda&#8230; Part\u00ed nervioso y concentrado, el primer kil\u00f3metro lo corr\u00ed en 3:40, y el segundo kil\u00f3metro en 3:50. Yo sent\u00eda que hab\u00eda corrido con la misma intensidad ambos, pero el terreno es tan disparejo, de subir y bajar, que me dije a mi mismo, <strong><em>\u00absi sigues mirando el reloj por cada kil\u00f3metro te desgastar\u00e1s, no disfrutar\u00e1s y si no logras mantener el ritmo te frustrar\u00e1s\u00bb<\/em><\/strong>, en ese momento no mire m\u00e1s mi reloj, solo mire el p\u00fablico y saqu\u00e9 mi primera sonrisa, la gente lo not\u00f3 y me comenz\u00f3 a gritar <em><strong>CHILE!!!<\/strong><\/em> <br>Cada vez que me gritaban yo les empu\u00f1aba mi mano y ellos lo celebraban, luego disfrut\u00e9 de chocar las manos con los ni\u00f1os a las orillas del camino, ellos se pon\u00edan muy felices, tal vez pensaban que yo era alg\u00fan corredor importante, y volv\u00eda a escuchar el <em>CHILE, CHILE<\/em> nuevamente. A esa altura mi sonrisa no desaparec\u00eda de mi cara, ya me sent\u00eda un protagonista de este evento, incluso otros corredores reconoc\u00edan lo qu\u00e9 pasaba y me dec\u00edan <em>\u00abCHILENO la gente te quiere\u00bb<\/em>, yo disfrutaba cada metro que recorr\u00eda&#8230;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Despu\u00e9s de subir y bajar tantos kil\u00f3metros mis caderas me dol\u00edan, mis piernas estaban cansadas, y en el kil\u00f3metro 35 baj\u00e9 la cabeza pensando por un segundo que deb\u00eda parar para que se me pasaran los dolores, pero adivinen <em>jajajaja<\/em>&#8230; Nuevamente escuch\u00e9 un grito muy fuerte de <strong><em>\u00abCHILEEE \u00ab<\/em><\/strong> y nuestra bandera en el p\u00fablico, una joven me gritaba como loca <em><strong>VAMOS CHILENO TU PUEDES!!<\/strong><\/em> <br>Fue mi segundo aire, levant\u00e9 mi cara, sonre\u00ed y grit\u00e9 un <em>C-H-I <\/em> con ella para retribuir su energ\u00eda&#8230; Eso me trajo de vuelta en la carrera, me impuls\u00f3 a seguir corriendo, y comenc\u00e9 a entrar en ritmo nuevamente. A esa altura pasaba y pasaba competidores que ya ven\u00edan exhaustos por el desgaste, yo estaba con energ\u00eda, corriendo mejor, y festejando con todo el p\u00fablico, era incre\u00edble, me ve\u00edan feliz y lo aplaud\u00edan, gente de muchos pa\u00edses conmigo, ellos alentando, gritando y aplaudiendo, y yo corriendo feliz y fuerte. <\/p>\n\n\n\n<p>Llegando a la meta empu\u00f1\u00e9 mi mano, mir\u00e9 a todo el p\u00fablico y luego abr\u00ed los brazos. Lo celebr\u00e9 con todos y me sent\u00ed como un gran corredor o mejor a\u00fan, como un GRAN MARATONISTA, exponente de la salud y el deporte en un pa\u00eds que no es el m\u00edo, pero me hizo sentir m\u00e1s <strong>CHILENO que nunca<\/strong>, ellos vieron mi esfuerzo por <strong>2 horas y 41 minutos<\/strong> a tope, hoy me siento feliz, me siento exitoso, me siento un ganador pleno!!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/www.instagram.com\/src_pantera\/\" data-type=\"URL\" data-id=\"https:\/\/www.instagram.com\/src_pantera\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" width=\"723\" height=\"821\" class=\"wp-image-1909\" style=\"width: 600px;\" src=\"https:\/\/www.mundorunning.cl\/app\/wp-content\/uploads\/2022\/04\/JBarreraBoston22B.jpeg\" alt=\"\" srcset=\"https:\/\/www.mundorunning.cl\/app\/wp-content\/uploads\/2022\/04\/JBarreraBoston22B.jpeg 723w, https:\/\/www.mundorunning.cl\/app\/wp-content\/uploads\/2022\/04\/JBarreraBoston22B-264x300.jpeg 264w\" sizes=\"(max-width: 723px) 100vw, 723px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jonathan Barrera fue uno de los chilenos m\u00e1s veloces en la 126\u00b0 edici\u00f3n del \u00abBoston Marathon\u00bb, carrera que disfrut\u00f3 de principio a fin, pero que tambi\u00e9n present\u00f3 algunos obst\u00e1culos. <\/p>\n","protected":false},"author":1,"featured_media":1910,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7,8,9,4],"tags":[149,44,18,168,26,23,19],"_links":{"self":[{"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/posts\/1907"}],"collection":[{"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/comments?post=1907"}],"version-history":[{"count":13,"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/posts\/1907\/revisions"}],"predecessor-version":[{"id":1929,"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/posts\/1907\/revisions\/1929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/media\/1910"}],"wp:attachment":[{"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/media?parent=1907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/categories?post=1907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/tags?post=1907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}