{"id":1348,"date":"2022-04-21T22:23:54","date_gmt":"2022-04-21T22:23:54","guid":{"rendered":"https:\/\/www.mundorunning.cl\/app\/?p=1348"},"modified":"2022-04-23T11:46:44","modified_gmt":"2022-04-23T11:46:44","slug":"centralrunarica2022","status":"publish","type":"post","link":"https:\/\/www.mundorunning.cl\/app\/noticias-recientes\/centralrunarica2022\/","title":{"rendered":"\u00abCentral Run Arica 2022\u00bb espera a los mejores Trail Runners del pa\u00eds"},"content":{"rendered":"\n<p>En su cuarta edici\u00f3n<strong> <a rel=\"noreferrer noopener\" href=\"https:\/\/welcu.com\/norte-outdoor-y-tra-eventos\/central-run-2022\" data-type=\"URL\" data-id=\"https:\/\/welcu.com\/norte-outdoor-y-tra-eventos\/central-run-2022\" target=\"_blank\">\u00abCENTRAL RUN ARICA 2022\u00bb<\/a><\/strong> espera congregar a los m\u00e1s experimentados corredores de Trail Running del pa\u00eds, ya que realizar\u00e1n este evento el 16 de julio y contempla por primera vez un ultramarat\u00f3n dentro de los distintos circuitos que tienen planificados para que los participantes de todos los niveles puedan disfrutar este desaf\u00edo. <\/p>\n\n\n\n<p>Las rutas tendr\u00e1n su punto de partida en el <strong>Valle de Lluta<\/strong>, y los recorridos tienen distancias de 8, 16, 30 y 55 kil\u00f3metros. Las inscripciones ya se encuentran disponibles a trav\u00e9s de <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/welcu.com\/norte-outdoor-y-tra-eventos\/central-run-2022\" data-type=\"URL\" data-id=\"https:\/\/welcu.com\/norte-outdoor-y-tra-eventos\/central-run-2022\" target=\"_blank\">WELCU<\/a><\/strong>, y son cientos de personas las que ya est\u00e1n registradas en la prueba, por lo que la fiesta del trail en el extremo norte del pa\u00eds est\u00e1 garantizada. <\/p>\n\n\n\n<p>Los organizadores, <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/traeventosdeportivos\/?hl=es-la\" data-type=\"URL\" data-id=\"https:\/\/www.instagram.com\/traeventosdeportivos\/?hl=es-la\" target=\"_blank\">Tra Eventos Deportivos<\/a><\/strong> y <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/norteoutdoor\/?hl=es-la\" data-type=\"URL\" data-id=\"https:\/\/www.instagram.com\/norteoutdoor\/?hl=es-la\" target=\"_blank\">Norte Outdoor<\/a><\/strong>, tienen todo preparado para que los participantes vivan una gran experiencia en la Regi\u00f3n de Arica y Parinacota, ya que esperan que \u00abnuestra regi\u00f3n sea vista y reconocida como un destino deportivo-tur\u00edstico, en donde puedan venir a competir y adem\u00e1s disfrutar de unos d\u00edas en nuestra regi\u00f3n, conociendo los distintos atractivos que presenta la zona, como son nuestras playas, valles y pueblos de la cordillera\u00bb, se\u00f1ala <strong>Manuel Cortez<\/strong>, de <strong>Tra Eventos Deportivos<\/strong>. <\/p>\n\n\n\n<p>Todas las rutas en competencia pasar\u00e1n por la hist\u00f3rica <strong>Estaci\u00f3n de Trenes Central<\/strong>, lugar emblem\u00e1tico de la red ferroviaria del siglo pasado entre Arica y La Paz, Bolivia, y que da nombre al importante desaf\u00edo de julio pr\u00f3ximo. Esta particularidad hist\u00f3rica deportiva del evento aumenta cada a\u00f1o la atenci\u00f3n de los corredores que vienen desde distintas partes de Chile, Per\u00fa y Bolivia.<\/p>\n\n\n\n<p>Este a\u00f1o la animaci\u00f3n de la competencia la realizar\u00e1 <strong>Cristian Valencia<\/strong>, <strong><em><a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/lavozdeltrail\/\" target=\"_blank\">La voz del Trail<\/a><\/em><\/strong>, quien le otorgar\u00e1 todo el glamour a las instancias m\u00e1s importantes del evento, principalmente a las llegadas de cada competidor cuando crucen la meta.<\/p>\n\n\n\n<p>A continuaci\u00f3n puedes revisar el video del evento realizado el 2019: <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Central Run 2019\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/4A1kFAqsCkE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em><strong><a href=\"https:\/\/welcu.com\/norte-outdoor-y-tra-eventos\/central-run-2022\" data-type=\"URL\" data-id=\"https:\/\/welcu.com\/norte-outdoor-y-tra-eventos\/central-run-2022\" target=\"_blank\" rel=\"noreferrer noopener\">SUMATE a este espectacular evento Trail Running en el extremo norte de Chile!!<\/a><\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/welcu.com\/norte-outdoor-y-tra-eventos\/central-run-2022\" data-type=\"URL\" data-id=\"https:\/\/welcu.com\/norte-outdoor-y-tra-eventos\/central-run-2022\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" width=\"500\" height=\"920\" class=\"wp-image-1349\" style=\"width: 400px;\" src=\"https:\/\/www.mundorunning.cl\/app\/wp-content\/uploads\/2022\/03\/CENTRAL_RUN_ARICA_AFICHE.jpeg\" alt=\"\" srcset=\"https:\/\/www.mundorunning.cl\/app\/wp-content\/uploads\/2022\/03\/CENTRAL_RUN_ARICA_AFICHE.jpeg 500w, https:\/\/www.mundorunning.cl\/app\/wp-content\/uploads\/2022\/03\/CENTRAL_RUN_ARICA_AFICHE-163x300.jpeg 163w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 16 de julio Arica se llena de Trail Running con este evento que tendr\u00e1 distancias para todos los niveles de corredores. <\/p>\n","protected":false},"author":1,"featured_media":1360,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,10],"tags":[123,44,122,18,23,19,20],"_links":{"self":[{"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/posts\/1348"}],"collection":[{"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/comments?post=1348"}],"version-history":[{"count":7,"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/posts\/1348\/revisions"}],"predecessor-version":[{"id":1931,"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/posts\/1348\/revisions\/1931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/media\/1360"}],"wp:attachment":[{"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/media?parent=1348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/categories?post=1348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundorunning.cl\/app\/wp-json\/wp\/v2\/tags?post=1348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}